{"id":10017095,"date":"2021-05-11T12:27:48","date_gmt":"2021-05-11T10:27:48","guid":{"rendered":"https:\/\/graubuendentrailrun.ch\/event\/repower-seelaufserie-davos\/"},"modified":"2021-05-11T12:27:48","modified_gmt":"2021-05-11T10:27:48","slug":"repower-seelaufserie-davos","status":"publish","type":"tribe_events","link":"https:\/\/graubuendentrailrun.ch\/it\/event\/repower-seelaufserie-davos\/2026-07-28\/","title":{"rendered":"Repower Seelaufserie Davos"},"content":{"rendered":"<p>Il lago di Davos offre un percorso e una cornice ideali per le gare di corsa. Qui, grandi e piccini possono confrontarsi su diverse distanze e categorie di et\u00e0. Questa tradizione deve essere preservata anche per le generazioni future.  <\/p>\n<p><a href=\"https:\/\/www.trackclub.ch\/seelauf\" target=\"_blank\" rel=\"noopener\">Scopri di pi\u00f9<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il lago di Davos offre un percorso e una cornice ideali per le gare di corsa. Qui, grandi e piccini possono confrontarsi su diverse distanze e categorie di et\u00e0. Questa [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15745,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[58],"class_list":["post-10017095","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-eventi-di-corsa","cat_eventi-di-corsa","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"_links":{"self":[{"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/tribe_events\/10017095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":0,"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/tribe_events\/10017095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/media\/15745"}],"wp:attachment":[{"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/media?parent=10017095"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/tags?post=10017095"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/graubuendentrailrun.ch\/it\/wp-json\/wp\/v2\/tribe_events_cat?post=10017095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}